{"id":8703,"date":"2022-02-15T06:14:52","date_gmt":"2022-02-15T06:14:52","guid":{"rendered":"https:\/\/rcbo.org\/?page_id=8703"},"modified":"2023-01-18T02:41:20","modified_gmt":"2023-01-18T10:41:20","slug":"strategic-plan","status":"publish","type":"page","link":"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/","title":{"rendered":"Plan estrat\u00e9gico"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8703\" class=\"elementor elementor-8703 elementor-2603\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45f4254 elementor-section-stretched strategic-plan-welcome-panel bishop-lines elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45f4254\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3cb8bf02\" data-id=\"3cb8bf02\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-783b8e8e align-items-center elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"783b8e8e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-15a9b806 left\" data-id=\"15a9b806\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaa53e elementor-widget elementor-widget-image\" data-id=\"aaa53e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"669\" height=\"654\" src=\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/20210714-2021.jpg\" class=\"attachment-full size-full wp-image-109313\" alt=\"\" srcset=\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/20210714-2021.jpg 669w, https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/20210714-2021-300x293.jpg 300w\" sizes=\"(max-width: 669px) 100vw, 669px\" style=\"width:100%;height:97.76%;max-width:669px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-232792a9 right\" data-id=\"232792a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78012e75 elementor-widget elementor-widget-text-editor\" data-id=\"78012e75\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Queridos hermanos y hermanas en Cristo, la naturaleza de la vida cristiana es estar en \u201cmisi\u00f3n\u201d, lo cual ciertamente se encuentra en los documentos del Concilio Vaticano II y especialmente en los escritos de los Santos Papa Pablo VI y Juan Pablo II. Ahora m\u00e1s que nunca, como encargados de los misterios de Dios, y con puestos de responsabilidad en la vida, ense\u00f1anza y culto de la Iglesia, debemos tener clara esta Misi\u00f3n de la Iglesia, dando testimonio de Jes\u00fas entre nosotros, viviendo su Mensaje evang\u00e9lico de amor, humildad y caridad, e invitando a \u201ctodas las naciones\u201d a convertirse en sus disc\u00edpulos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a4bbd89 btn-primary white btn-strategic elementor-widget elementor-widget-button\" data-id=\"3a4bbd89\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/wp-content\/uploads\/2022\/02\/Bishops-Letter-Page.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leer m\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc8a6d9 elementor-section-full_width elementor-section-stretched bishop-lines elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"cc8a6d9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-677958a2\" data-id=\"677958a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-26b5f827 elementor-section-full_width align-items-center elementor-section-height-default elementor-section-height-default\" data-id=\"26b5f827\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1cee33fb left\" data-id=\"1cee33fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-140489b4 elementor-widget elementor-widget-image\" data-id=\"140489b4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"700\" src=\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/Bishop-Vann-BW.png\" class=\"attachment-full size-full wp-image-109317\" alt=\"\" srcset=\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/Bishop-Vann-BW.png 700w, https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/Bishop-Vann-BW-300x300.png 300w, https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/Bishop-Vann-BW-150x150.png 150w, https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/Bishop-Vann-BW-120x120.png 120w\" sizes=\"(max-width: 700px) 100vw, 700px\" style=\"width:100%;height:100%;max-width:700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-30710768 right\" data-id=\"30710768\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15bfee82 elementor-widget elementor-widget-text-editor\" data-id=\"15bfee82\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"large\">\u00abDear Brothers and Sisters in christ,<\/span><br \/>The nature of the Christian life is to be on \u00abmisssion\u00bb, which is certainly to be found in the documents of the Second Vatican Councile and especially in the writings of Saint Pope Paul VI nad John Paul II. Now more than ever, as those entrusted with the mysteries of God, and with positions of the responsibility in the life, teaching and worship of the Church, we must be clear about this Mission of the Church, giving witness to Jesus among us, Living His Gospel message of love, humility and charity, and inviting \u00aball nations\u00bb to become disciples of Him.\u00bb<\/p><p><a class=\"btn-primary white\" style=\"padding-left: 0;\" href=\"\/wp-content\/uploads\/2022\/01\/Bishops-Letter-Page-V3.pdf\" target=\"_blank\" rel=\"noopener\">READ MORE<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68d917c elementor-section-stretched plan-type-list elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68d917c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66ae349\" data-id=\"66ae349\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d0e800f plan-type elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0e800f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a2858a2 para para-left\" data-id=\"a2858a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4594aa7 text-transform-none elementor-widget elementor-widget-heading\" data-id=\"4594aa7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mayordom\u00eda y Finanzas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ff06f7a video\" data-id=\"ff06f7a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e14cb17 elementor-widget elementor-widget-html\" data-id=\"e14cb17\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe src=\"https:\/\/player.vimeo.com\/video\/377151428?h=08b5586296\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-36b9a01 plan-type elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36b9a01\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-79d356f video\" data-id=\"79d356f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6430997 elementor-widget elementor-widget-html\" data-id=\"6430997\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe src=\"https:\/\/player.vimeo.com\/video\/363946284?h=52de41acaf\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7b674ff para para-right\" data-id=\"7b674ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eb7394 text-transform-none elementor-widget elementor-widget-heading\" data-id=\"5eb7394\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Educaci\u00f3n de las escuelas cat\u00f3licas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f36dfce plan-type elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f36dfce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-60e2255 para para-left\" data-id=\"60e2255\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-915aec6 text-transform-none elementor-widget elementor-widget-heading\" data-id=\"915aec6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Evangelizaci\u00f3n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9698d18 video\" data-id=\"9698d18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aed1829 elementor-widget elementor-widget-html\" data-id=\"aed1829\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe src=\"https:\/\/player.vimeo.com\/video\/360896326?h=507bedd556\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-91b635b plan-type elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"91b635b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a449496 video\" data-id=\"a449496\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad60c66 elementor-widget elementor-widget-html\" data-id=\"ad60c66\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe src=\"https:\/\/player.vimeo.com\/video\/359873266?h=c559f2e959\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5b23869 para para-right\" data-id=\"5b23869\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b527b3 text-transform-none elementor-widget elementor-widget-heading\" data-id=\"0b527b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gobernanza y Liderazgo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3631443 plan-type elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3631443\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a31517f para para-left\" data-id=\"a31517f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-920f1a4 text-transform-none elementor-widget elementor-widget-heading\" data-id=\"920f1a4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formaci\u00f3n del Clero<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c5b2bf video\" data-id=\"5c5b2bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47ad200 elementor-widget elementor-widget-html\" data-id=\"47ad200\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe src=\"https:\/\/player.vimeo.com\/video\/359850153?h=5b55b4d66e\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"Queridos hermanos y hermanas en Cristo, la naturaleza de la vida cristiana es estar en \u201cmisi\u00f3n\u201d, lo cual ciertamente se encuentra en los documentos del Concilio Vaticano II y especialmente en los escritos de los Santos Papa Pablo VI y Juan Pablo II. Ahora m\u00e1s que nunca, como encargados de los misterios de Dios, y&#8230;","protected":false},"author":1,"featured_media":162444,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"passster_activate_protection":null,"passster_protect_child_pages":"","passster_protection_type":"password","passster_password":"","passster_activate_overwrite_defaults":"","passster_headline":"","passster_instruction":"","passster_placeholder":"","passster_button":"","passster_id":"","passster_activate_misc_settings":"","passster_redirect_url":"","passster_hide":"no","passster_area_shortcode":"","footnotes":""},"coauthors":[2407],"class_list":["post-8703","page","type-page","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plan estrat\u00e9gico - nombre del RCBO<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan estrat\u00e9gico - nombre del RCBO\" \/>\n<meta property=\"og:description\" content=\"Queridos hermanos y hermanas en Cristo, la naturaleza de la vida cristiana es estar en \u201cmisi\u00f3n\u201d, lo cual ciertamente se encuentra en los documentos del Concilio Vaticano II y especialmente en los escritos de los Santos Papa Pablo VI y Juan Pablo II. Ahora m\u00e1s que nunca, como encargados de los misterios de Dios, y...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/\" \/>\n<meta property=\"og:site_name\" content=\"RCBO\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-18T10:41:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/20210714-2021.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"rcbo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/\",\"url\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/\",\"name\":\"Plan estrat\u00e9gico - nombre del RCBO\",\"isPartOf\":{\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2024\/01\/ChristCathedralCampus03-large-scaled.jpg\",\"datePublished\":\"2022-02-15T06:14:52+00:00\",\"dateModified\":\"2023-01-18T10:41:20+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/#primaryimage\",\"url\":\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2024\/01\/ChristCathedralCampus03-large-scaled.jpg\",\"contentUrl\":\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2024\/01\/ChristCathedralCampus03-large-scaled.jpg\",\"width\":1582,\"height\":2048},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/#website\",\"url\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/\",\"name\":\"RCBO\",\"description\":\"The Roman Catholic Diocese of Orange\",\"publisher\":{\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/#organization\",\"name\":\"Di\u00f3cesis Cat\u00f3lica Romana de Orange\",\"alternateName\":\"RCBO\",\"url\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2021\/12\/logo-black.png\",\"contentUrl\":\"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2021\/12\/logo-black.png\",\"width\":215,\"height\":59,\"caption\":\"Di\u00f3cesis Cat\u00f3lica Romana de Orange\"},\"image\":{\"@id\":\"https:\/\/dioceseofocstg.wpengine.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan estrat\u00e9gico - nombre del RCBO","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Plan estrat\u00e9gico - nombre del RCBO","og_description":"Queridos hermanos y hermanas en Cristo, la naturaleza de la vida cristiana es estar en \u201cmisi\u00f3n\u201d, lo cual ciertamente se encuentra en los documentos del Concilio Vaticano II y especialmente en los escritos de los Santos Papa Pablo VI y Juan Pablo II. Ahora m\u00e1s que nunca, como encargados de los misterios de Dios, y...","og_url":"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/","og_site_name":"RCBO","article_modified_time":"2023-01-18T10:41:20+00:00","og_image":[{"url":"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2023\/01\/20210714-2021.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos","Written by":"rcbo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/","url":"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/","name":"Plan estrat\u00e9gico - nombre del RCBO","isPartOf":{"@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/#primaryimage"},"image":{"@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2024\/01\/ChristCathedralCampus03-large-scaled.jpg","datePublished":"2022-02-15T06:14:52+00:00","dateModified":"2023-01-18T10:41:20+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/strategic-plan\/#primaryimage","url":"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2024\/01\/ChristCathedralCampus03-large-scaled.jpg","contentUrl":"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2024\/01\/ChristCathedralCampus03-large-scaled.jpg","width":1582,"height":2048},{"@type":"WebSite","@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/#website","url":"https:\/\/dioceseofocstg.wpengine.com\/es\/","name":"RCBO","description":"The Roman Catholic Diocese of Orange","publisher":{"@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dioceseofocstg.wpengine.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/#organization","name":"Di\u00f3cesis Cat\u00f3lica Romana de Orange","alternateName":"RCBO","url":"https:\/\/dioceseofocstg.wpengine.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2021\/12\/logo-black.png","contentUrl":"https:\/\/dioceseofocstg.wpengine.com\/wp-content\/uploads\/2021\/12\/logo-black.png","width":215,"height":59,"caption":"Di\u00f3cesis Cat\u00f3lica Romana de Orange"},"image":{"@id":"https:\/\/dioceseofocstg.wpengine.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/dioceseofocstg.wpengine.com\/es\/wp-json\/wp\/v2\/pages\/8703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dioceseofocstg.wpengine.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dioceseofocstg.wpengine.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dioceseofocstg.wpengine.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dioceseofocstg.wpengine.com\/es\/wp-json\/wp\/v2\/comments?post=8703"}],"version-history":[{"count":0,"href":"https:\/\/dioceseofocstg.wpengine.com\/es\/wp-json\/wp\/v2\/pages\/8703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dioceseofocstg.wpengine.com\/es\/wp-json\/wp\/v2\/media\/162444"}],"wp:attachment":[{"href":"https:\/\/dioceseofocstg.wpengine.com\/es\/wp-json\/wp\/v2\/media?parent=8703"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/dioceseofocstg.wpengine.com\/es\/wp-json\/wp\/v2\/coauthors?post=8703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}